{"id":11317,"date":"2021-02-07T19:48:52","date_gmt":"2021-02-07T19:48:52","guid":{"rendered":"https:\/\/theologie.whp.uzh.ch\/apps\/gpi\/?p=11317"},"modified":"2023-03-06T22:42:32","modified_gmt":"2023-03-06T21:42:32","slug":"joao-6-51-58","status":"publish","type":"post","link":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/joao-6-51-58\/","title":{"rendered":"Jo\u00e3o 6.51-58,"},"content":{"rendered":"<h3 align=\"left\"><strong>13\u00ba Domingo Ap\u00f3s Pentecostes \u2013 03 de setembro de 2006<\/strong><br \/>\n<strong>Jo 6.51-58, Leandro D. H\u00fcbner<\/strong><\/h3>\n<hr \/>\n<div align=\"left\">Estimados irm\u00e3os e irm\u00e3s em Cristo.Estamos novamente na \u00e9poca de campanha eleitoral. Os candidatos, especialmente a presidente e governadores, falam bastante de educa\u00e7\u00e3o, seguran\u00e7a, emprego, alimento e sa\u00fade para o povo. No seu primeiro mandato, o presidente Lula lan\u00e7ou o programa Fome Zero, do qual havia falado quando era candidato. Muitos dizem que o Fome Zero n\u00e3o saiu do ch\u00e3o, outros dizem que funciona bem. Mas, se hoje o presidente ou um dos outros candidatos fosse convidar algu\u00e9m pra fazer um programa assim decolar, certamente o melhor candidato seria Jesus, pois, no in\u00edcio do capitulo 6 de Jo\u00e3o, Jesus tinha alimentado mais de 5 mil homens, mulheres e crian\u00e7as com apenas 5 p\u00e3es e 2 peixes. E Em Mt 15 ele aparece alimentando outra multid\u00e3o de mais de 4 mil pessoas com 7 p\u00e3es e alguns peixinhos.<\/p>\n<p>Jesus seria a pessoa ideal para matar a fome do nosso povo, sendo um ministro de governo especial. Quem n\u00e3o gostaria de ter um ministro ou presidente assim, que alimentasse o povo sem gastar quase nada?<\/p>\n<p>Era isso que grande parte das pessoas alimentadas por Jesus estava pensando quando o procuraram de novo no dia seguinte. Queriam matar a fome \u2013 queriam p\u00e3o! Jesus lhes diz ent\u00e3o que seu Pai d\u00e1 um p\u00e3o que desce do c\u00e9u e que d\u00e1 vida ao mundo, e o povo pede: <em>Queremos que o senhor nos d\u00ea sempre desse p\u00e3o!<\/em><\/p>\n<p>Nesse ponto Jesus entra no assunto que lemos no evangelho de hoje, com uma conversa estranha de que Ele \u00e9 o p\u00e3o vivo que desceu do c\u00e9u. No v. 51 Jesus diz: <em>Eu sou o p\u00e3o vivo que desceu do c\u00e9u. Se algu\u00e9m comer desse p\u00e3o, viver\u00e1 para sempre. E o p\u00e3o que eu darei para que o mundo tenha vida \u00e9 a minha carne.<\/em><\/p>\n<p>Imaginem a surpresa daquelas pessoas \u2013 buscavam p\u00e3o e Jesus lhes oferece a sua carne! E n\u00e3o s\u00f3 isso, vejam o v. 53: <em>Eu afirmo a voc\u00eas que isto \u00e9 verdade: se voc\u00eas n\u00e3o comerem a carne do Filho do Homem e n\u00e3o beberem o seu sangue, voc\u00eas n\u00e3o ter\u00e3o vida.<\/em> Para n\u00f3s, que sabemos que Jesus derramou o seu sangue na cruz e sacrificou ali o seu corpo e, antes disso, instituiu a Santa Ceia, n\u00e3o \u00e9 t\u00e3o dif\u00edcil aceitar o que Jesus disse. Mas, para eles, isso era um absurdo!<\/p>\n<p>A verdade, irm\u00e3os, \u00e9 que Deus sabe que necessitamos de p\u00e3o \u2013 para o corpo e para a alma. No AT Deus alimentou seu povo no deserto com o man\u00e1, o p\u00e3o que ca\u00eda do c\u00e9u todos os dias, durante 40 anos. No NT, Cristo multiplicou p\u00e3es e peixes para alimentar as pessoas, al\u00e9m de curar seus corpos de doen\u00e7as e males. Mesmo assim, muitos se rebelaram contra Deus, desprezando o man\u00e1, como lemos em Nm 11. Estes, diz a B\u00edblia, foram condenados por Deus.<\/p>\n<p>Para alma, Deus tamb\u00e9m nos enviou p\u00e3o, o P\u00e3o da Vida, Jesus. Ele se tornou nosso alimento pelo sacrif\u00edcio de sua carne e derramamento do seu sangue. Mas, muitos tamb\u00e9m rejeitaram Jesus, zombando dele: <em>Como \u00e9 que este homem pode dar a sua pr\u00f3pria carne para a gente comer?<\/em> (v. 52) Muitos hoje tamb\u00e9m rejeitam o P\u00e3o da Vida, e a esses Jesus diz: <em>Eu afirmo a voc\u00eas que isto \u00e9 verdade: se voc\u00eas n\u00e3o comerem a carne do Filho do Homem e n\u00e3o beberem o seu sangue, voc\u00eas n\u00e3o ter\u00e3o vida<\/em> (v. 53).<\/p>\n<p>Por isso, meu irm\u00e3o e irm\u00e3, <strong>coma o p\u00e3o vivo e viva para sempre<\/strong>! Jesus diz: <em>Quem come a minha carne e bebe o meu sangue tem a vida eterna, e eu o ressuscitarei no \u00faltimo dia. Este \u00e9 o p\u00e3o que desceu do c\u00e9u. N\u00e3o \u00e9 como o p\u00e3o que os antepassados de voc\u00eas comeram e mesmo assim morreram. Quem come deste p\u00e3o viver\u00e1 para sempre (<\/em>v. 54 e 58).<\/p>\n<p>Aqueles que comeram o man\u00e1 no deserto morreram, assim como n\u00f3s vamos morrer fisicamente um dia, n\u00e3o importa se nos alimentamos muito ou pouco, bem ou mal. Mas, em Jesus, n\u00f3s temos a vida que n\u00e3o \u00e9 destru\u00edda pela morte. No v. 57 ele nos diz: <em>O Pai, que tem a vida, foi quem me enviou, e por causa dele eu tenho a vida. Assim, tamb\u00e9m, quem se alimenta de mim ter\u00e1 vida por minha causa<\/em>. E em Ap 1.18 afirma: <em>Eu sou aquele que vive. Estive morto, mas agora estou vivo para todo o sempre. Tenho autoridade sobre a morte e sobre o mundo dos mortos. <\/em> Comer o p\u00e3o vivo garante a vida eterna!<\/p>\n<p><strong> Coma o p\u00e3o vivo e viva para sempre<\/strong> ! Jesus deixa claro que o p\u00e3o vivo, que \u00e9 ele, \u00e9 para ser comido e n\u00e3o apenas admirado. Assim como n\u00e3o serviria para nada Jesus multiplicar p\u00e3es se esses n\u00e3o fossem comidos pelo povo, e n\u00e3o adianta ficarmos s\u00f3 admirando um p\u00e3o bonito que ganhamos ou compramos, sem com\u00ea-lo, o p\u00e3o vivo que desceu do c\u00e9u \u00e9 para ser comido e n\u00e3o admirado. Por isso Jesus diz: <em>Eu sou o p\u00e3o vivo que desceu do c\u00e9u. Se algu\u00e9m comer desse p\u00e3o, viver\u00e1 para sempre. E o p\u00e3o que eu darei para que o mundo tenha vida \u00e9 a minha carne. Eu afirmo a voc\u00eas que isto \u00e9 verdade: se voc\u00eas n\u00e3o comerem a carne do Filho do Homem e n\u00e3o beberem o seu sangue, voc\u00eas n\u00e3o ter\u00e3o vida<\/em> (v. 51,53).<\/p>\n<p>Jesus n\u00e3o quer admiradores, crist\u00e3os que o admiram de longe, sem compromisso e sem envolvimento com ele. Jesus, o p\u00e3o vivo, deve ser comido por n\u00f3s, de duas formas:<\/p>\n<ul>\n<li>pela f\u00e9, como ele diz no v. 47: <em>quem cr\u00ea tem a vida eterna<\/em>.<\/li>\n<li>no sacramento da SC, onde ele nos diz: <em>comam, isto \u00e9 o meu corpo; bebam, isto \u00e9 o meu sangue.<\/em><\/li>\n<\/ul>\n<p>Comer um p\u00e3o exige e envolve a\u00e7\u00e3o \u2013 pegar o p\u00e3o, mastig\u00e1-lo e engoli-lo. Comer o p\u00e3o vivo \u2013 Jesus \u2013 exige e envolve a\u00e7\u00e3o tamb\u00e9m: crer, comer e beber Cristo!<\/p>\n<p><strong> Coma o p\u00e3o vivo e viva para sempre<\/strong> ! O p\u00e3o vivo \u00e9 para todos, pois Deus oferece sua gra\u00e7a a todas as pessoas, como lemos em Is 55.1-2: <em>O Senhor Deus diz: Escutem os que t\u00eam sede: venham beber \u00e1gua! Venham, os que n\u00e3o t\u00eam dinheiro: comprem comida e comam! Venham e comprem leite e vinho, que tudo \u00e9 de gra\u00e7a. Por que voc\u00eas gastam dinheiro com o que n\u00e3o \u00e9 comida? Por que gastam o seu sal\u00e1rio com coisas que n\u00e3o matam a fome? Se ouvirem e fizerem o que eu ordeno, voc\u00eas comer\u00e3o do melhor alimento, ter\u00e3o comidas gostosas<\/em>. Muitos assim mesmo preferem passar fome espiritual, rejeitando o p\u00e3o da vida:<\/p>\n<ul>\n<li>Muitos n\u00e3o cr\u00eaem em Jesus como seu Salvador \u2013 muitos nem o conhecem;<\/li>\n<li>Muitos buscam Jesus apenas para ganhar o p\u00e3o material \u2013 querem dele curas, milagres, dinheiro, fartura, etc.;<\/li>\n<li>Outros apenas admiram Jesus como um grande mestre, pregador do amor e da paz;<\/li>\n<li>Outras ainda ouvem sua Palavra, conhecem sua vontade, mas na \u201chora h\u201d o abandonam, pois querem receber dele apenas benef\u00edcios e privil\u00e9gios, mas n\u00e3o querem saber de compromissos no reino de Cristo.<\/li>\n<\/ul>\n<p align=\"left\">Em qual destes grupos voc\u00ea se encaixa? Voc\u00ea \u00e9 um daqueles que n\u00e3o cr\u00ea? Ou \u00e9 um que busca Jesus s\u00f3 para as coisas materiais, ou na hora do aperto? Voc\u00ea admira Jesus \u2013 e s\u00f3 isso? Ou voc\u00ea \u00e9 mais um daqueles que ouvem Jesus, mas quando ele exige a\u00e7\u00e3o \u2013 crer, comer e beber de Cristo, isto \u00e9, compromisso com ele e seu reino, voc\u00ea cai fora?<\/p>\n<p>Quando Jesus terminou essa conversa com o povo, muitos acharam dif\u00edcil aceitar seus ensinamentos e o abandonaram, como vemos nos v. 60 e 66. N\u00e3o o acompanharam mais, sa\u00edram de fininho, discretamente, sem alarde&#8230;<\/p>\n<p>N\u00e3o \u00e9 isso que vemos tamb\u00e9m entre n\u00f3s, irm\u00e3os e irm\u00e3s? Vejam os irm\u00e3os que abandonam Jesus em nossa congrega\u00e7\u00e3o: eles v\u00e3o deixando a Igreja \u2013 que \u00e9 o corpo de Cristo \u2013 e a f\u00e9 aos poucos \u2013 faltam num culto, dois, tr\u00eas&#8230;, n\u00e3o acham importante nem necess\u00e1rio participar de estudos b\u00edblicos, n\u00e3o d\u00e3o valor \u00e0 comunh\u00e3o com Cristo e com os irm\u00e3os na Santa Ceia, esquecem seu compromisso de sustentar o trabalho da igreja de Cristo com suas ofertas, n\u00e3o conseguem ter tempo para as coisas de Deus. Enfim, com diversas desculpas diferentes, muitos de n\u00f3s queremos esconder o que realmente acontece: achamos dif\u00edcil o que Jesus ensina e n\u00e3o queremos nos comprometer com ele nem com seu reino!<\/p>\n<p><strong> Coma o p\u00e3o vivo e viva para sempre<\/strong> ! Voc\u00ea tem comido Cristo pela f\u00e9 verdadeira nele? Pela participa\u00e7\u00e3o na SC? Quantas vezes voc\u00ea come e bebe Cristo na SC por m\u00eas, por ano? Nossa m\u00e9dia de participa\u00e7\u00e3o nos cultos n\u00e3o chega a 50% dos membros, e na SC n\u00e3o chega a 30% dos que s\u00e3o confirmados! Poucos d\u00e3o valor ao p\u00e3o vivo! E a\u00ed Jesus \u00e9 duro, n\u00e3o fala macio: <em>Eu afirmo a voc\u00eas que isto \u00e9 verdade: se voc\u00eas n\u00e3o comerem a carne do Filho do Homem e n\u00e3o beberem o seu sangue, voc\u00eas n\u00e3o ter\u00e3o vida<\/em> (v. 53).<\/p>\n<p><strong> Coma o p\u00e3o vivo e viva para sempre<\/strong> ! Naquele dia o povo perguntou a Jesus: <em>O que Deus quer que a gente fa\u00e7a? <\/em> E Jesus respondeu: <em>Ele quer que voc\u00eas creiam naquele que ele enviou!<\/em> Deus quer que a gente creia em Jesus, porque quer que a gente viva para sempre. Ele est\u00e1 oferecendo a voc\u00ea o p\u00e3o vivo \u2013 Jesus \u2013 de gra\u00e7a, no seu programa <em>Fome Espiritual Zero<\/em>. Ele quer saciar a sua alma com o p\u00e3o que faz viver para sempre. Para isso, ele s\u00f3 pede que voc\u00ea creia em Jesus e coma seu corpo e sangue.<\/p>\n<p>Saciados por Jesus, n\u00f3s somos transformados em agentes do <em>Fome Espiritual Zero<\/em>. Usando o lema do governo, podemos dizer assim: \u201c O crist\u00e3o que do p\u00e3o vivo come, ajudando o brasileiro que de Jesus tem fome\u201d.<\/p>\n<p><strong> Coma o p\u00e3o vivo e viva para sempre<\/strong> ! O p\u00e3o vivo, Jesus, est\u00e1 a\u00ed, de gra\u00e7a, na Palavra de Deus e na SC. N\u00e3o desperdice esse p\u00e3o, aproveite e sacie a sua alma e a de muitos, para viver para sempre! Am\u00e9m.<\/p>\n<hr \/>\n<p><strong> Leandro Daniel H\u00fcbner<br \/>\n<\/strong><strong>Dion\u00edsio Cerqueira \u2013 SC \u2013 Brasil<br \/>\n<\/strong><strong>Igreja Evang\u00e9lica Luterana do Brasil<br \/>\n<\/strong><strong><a href=\"mailto:ldh@temais.com.br\">ldh@temais.com.br<\/a>, <a href=\"mailto:ledahu@gmail.com\"> ledahu@gmail.com<br \/>\n<\/a><\/strong><strong><a href=\"http:\/\/www.ielb.org.br\/\" target=\"_blank\" rel=\"noopener\">www.ielb.org.br<\/a><\/strong><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>13\u00ba Domingo Ap\u00f3s Pentecostes \u2013 03 de setembro de 2006 Jo 6.51-58, Leandro D. H\u00fcbner Estimados irm\u00e3os e irm\u00e3s em Cristo.Estamos novamente na \u00e9poca de campanha eleitoral. Os candidatos, especialmente a presidente e governadores, falam bastante de educa\u00e7\u00e3o, seguran\u00e7a, emprego, alimento e sa\u00fade para o povo. No seu primeiro mandato, o presidente Lula lan\u00e7ou o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15569,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39,727,157,853,108,250,1185,3,112,109],"tags":[],"beitragende":[],"predigtform":[],"predigtreihe":[],"bibelstelle":[],"class_list":["post-11317","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-johannes","category-archiv","category-beitragende","category-bibel","category-current","category-kapitel-06-chapter-06","category-leandro-d-huebner","category-nt","category-port","category-predigten"],"_links":{"self":[{"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/posts\/11317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/comments?post=11317"}],"version-history":[{"count":1,"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/posts\/11317\/revisions"}],"predecessor-version":[{"id":17255,"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/posts\/11317\/revisions\/17255"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/media\/15569"}],"wp:attachment":[{"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/media?parent=11317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/categories?post=11317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/tags?post=11317"},{"taxonomy":"beitragende","embeddable":true,"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/beitragende?post=11317"},{"taxonomy":"predigtform","embeddable":true,"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/predigtform?post=11317"},{"taxonomy":"predigtreihe","embeddable":true,"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/predigtreihe?post=11317"},{"taxonomy":"bibelstelle","embeddable":true,"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/bibelstelle?post=11317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}