{"id":18299,"date":"2023-06-14T22:22:23","date_gmt":"2023-06-14T20:22:23","guid":{"rendered":"https:\/\/theologie.whp.uzh.ch\/apps\/gpi\/?p=18299"},"modified":"2023-06-14T22:22:23","modified_gmt":"2023-06-14T20:22:23","slug":"mateus-9-35-10-8","status":"publish","type":"post","link":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/mateus-9-35-10-8\/","title":{"rendered":"Mateus 9. 35-10.8"},"content":{"rendered":"<h3 style=\"font-weight: 400;\">PR\u00c9DICA PARA O 3. DOMINGO AP\u00d3S PENTECOSTES \u2013 18.06.2023 | Mateus 9. 35-10.8 | Marcos Aur\u00e9lio de Oliveira |<\/h3>\n<p style=\"font-weight: 400;\">\u201cA gra\u00e7a do Senhor Jesus Cristo, e o amor de Deus, e a comunh\u00e3o do Esp\u00edrito Santo sejam com todos v\u00f3s.\u201d 2 Cor\u00edntios 13.13. Am\u00e9m.<\/p>\n<p style=\"font-weight: 400;\">Prezada comunidade! Irm\u00e3os e irm\u00e3s!<\/p>\n<p style=\"font-weight: 400;\">Liturgicamente hoje estamos no terceiro domingo ap\u00f3s Pentecostes. No calend\u00e1rio lit\u00fargico Crist\u00e3o este \u00e9 o Ciclo do Tempo Comum&#8230;<\/p>\n<p style=\"font-weight: 400;\">Por falar nisso, voc\u00eas sabem quantos ciclos t\u00eam o calend\u00e1rio lit\u00fargico?<\/p>\n<p style=\"font-weight: 400;\">Vamos, rapidamente rever este conte\u00fado?<\/p>\n<p style=\"font-weight: 400;\">O calend\u00e1rio Lit\u00fargico \u00e9 composto por tr\u00eas ciclos: Ciclo do Natal, Ciclo da P\u00e1scoa e Ciclo do Tempo Comum&#8230;<\/p>\n<p style=\"font-weight: 400;\">O Ciclo do Natal \u00e9 o que inicia o Calend\u00e1rio Lit\u00fargico. Nele temos o Advento \u2013 tempo de prepara\u00e7\u00e3o, o Natal \u2013 nascimento de Jesus Cristo, Filho de Deus \u2013 Deus vem ao nosso encontro e recordamos isso quando celebramos nascimento de Jesus. E a Epifania \u2013 que \u00e9 a revela\u00e7\u00e3o de Jesus como Filho de Deus e Salvador nosso&#8230;<\/p>\n<p style=\"font-weight: 400;\">Na sequ\u00eancia do Calend\u00e1rio Lit\u00fargico temos o Ciclo da P\u00e1scoa que inicia com a Quarta-feira de Cinzas, inaugurando o per\u00edodo da Quaresma. Temos o Domingo de Ramos, que abre a Semana da Paix\u00e3o, na qual temos a Quinta-feira da Paix\u00e3o, a Sexta-feira da Paix\u00e3o (tamb\u00e9m conhecida como Sexta-feira Santa) e o Domingo de P\u00e1scoa \u2013 Dia da Ressurrei\u00e7\u00e3o de nosso Senhor. Ainda neste ciclo temos a Ascens\u00e3o (40 dias ap\u00f3s a P\u00e1scoa) e para fechar o ciclo: o Pentecostes (50 dias ap\u00f3s a P\u00e1scoa).<\/p>\n<p style=\"font-weight: 400;\">Ent\u00e3o chegamos ao ciclo que estamos agora: Ciclo do Tempo Comum. Esse ciclo iniciou com o Domingo da Trindade e encerra com o Domingo Cristo Rei, l\u00e1 em novembro. Ao todo ser\u00e3o 25 domingos. Este \u00e9 ciclo mais extenso&#8230;<\/p>\n<p style=\"font-weight: 400;\">Por que \u00e9 importante sabermos disso? Por que a Igreja Crist\u00e3 desenvolveu um calend\u00e1rio lit\u00fargico? Por que dividiu desta forma?<\/p>\n<p style=\"font-weight: 400;\">Bem, isso \u00e9 muito falado em Estudos B\u00edblicos e encontros do Ensino Confirmat\u00f3rio&#8230; e com a intencionalidade pedag\u00f3gica que quer nos ajudar a firmar e compreender os conte\u00fados de nossa f\u00e9.<\/p>\n<p style=\"font-weight: 400;\">Os dois primeiros ciclos mostram de forma muito forte a a\u00e7\u00e3o de Deus&#8230; no Natal Ele vem ao nosso encontro \u2013 ali j\u00e1 acontece o Evangelho \u2013 a Boa Nova, que Deus vem, elimina a dist\u00e2ncia que havia entre n\u00f3s e Ele&#8230; No Ciclo Pascal ent\u00e3o, para a humanidade que n\u00e3o o aceitou, rejeitou e o condenou, Ele respondeu, e novamente com amor, se entregando por n\u00f3s a morte. A qual n\u00e3o teve poder para segur\u00e1-lo e Ele foi ressuscitado, pois a vida vence a morte. No Pentecostes, que finaliza este ciclo, Deus envia seu Esp\u00edrito Santo, nosso Consolador, o esp\u00edrito Divino presente em cada qual de n\u00f3s&#8230;<\/p>\n<p style=\"font-weight: 400;\">Nos dois primeiros ciclos reconhecemos fortemente a a\u00e7\u00e3o de Deus&#8230; no Ciclo do Tempo Comum, e podemos dizer que esse \u00e9 o nosso ciclo, o das nossas respostas ao agir de Deus&#8230; Neste ciclo os textos B\u00edblicos, os Cultos, as festividades, sempre nos levar\u00e3o a olhar para a a\u00e7\u00e3o de Deus e nos apontar\u00e3o para as nossas respostas a esse agir&#8230;<\/p>\n<p style=\"font-weight: 400;\">Bem, isso que disse e apresentei at\u00e9 aqui foi para chamar a aten\u00e7\u00e3o que, quando celebramos um Culto, realizamos um estudo B\u00edblico, promovemos uma festividade, o que h\u00e1 como inten\u00e7\u00e3o \u00e9 refletirmos e fortalecermos nossa f\u00e9 e nosso agir em resposta a tudo o que Deus fez, faz e continuar\u00e1 fazendo por n\u00f3s, para n\u00f3s. N\u00e3o fazemos por fazer, ou para promo\u00e7\u00e3o desta ou daquela pessoa, mas porque como pessoas crist\u00e3s temos como tarefa, como miss\u00e3o: dar continuidade a obra de Jesus Cristo, nosso Senhor.<\/p>\n<p style=\"font-weight: 400;\">Com este pano de fundo olhamos para aos textos previstos para este terceiro domingo ap\u00f3s Pentecostes:<\/p>\n<p style=\"font-weight: 400;\">O texto da carta de Paulo aos Romanos fala da gra\u00e7a de Deus. Gra\u00e7a de Deus \u00e9 a\u00e7\u00e3o de Deus. \u00c9 aquilo que Ele faz por cada qual de n\u00f3s, sem que nada tenhamos para dar ou mere\u00e7amos ganhar. Isso \u00e9 gra\u00e7a! E gra\u00e7a n\u00e3o \u00e9 \u201cde gra\u00e7a\u201d. A gra\u00e7a de Deus \u00e9 cara. Custou a vida de seu filho! Isso ningu\u00e9m pode pagar para Deus. N\u00e3o foi de gra\u00e7a. Nem todo dinheiro deste mundo, nem toda e qualquer boa a\u00e7\u00e3o pagam a vida de Cristo na cruz. Isso \u00e9 gra\u00e7a. \u00c9 a\u00e7\u00e3o que nem merecemos, dada por amor, gerando muitos frutos!!!<\/p>\n<p style=\"font-weight: 400;\">Os frutos da gra\u00e7a de Deus s\u00e3o a compaix\u00e3o, a bondade, a miseric\u00f3rdia, o perd\u00e3o, a humildade, a comunh\u00e3o, a partilha e o amor.<\/p>\n<p style=\"font-weight: 400;\">Ent\u00e3o algu\u00e9m pode perguntar: \u201cPor que Deus deu a salva\u00e7\u00e3o para n\u00f3s sabendo que n\u00e3o merecemos?\u201d Porque s\u00f3 aquilo dado com amor e por amor pode transformar algu\u00e9m!!! E esta \u00e9 a centralidade do agir de Deus e aquilo que Ele tamb\u00e9m espera de n\u00f3s: Que amemos!<\/p>\n<p style=\"font-weight: 400;\">S\u00f3 o amor pode transformar pessoas pecadoras como n\u00f3s em pessoas que se doam para ajudar, porque j\u00e1 receberam miseric\u00f3rdia. Que perdoam porque j\u00e1 sentiram o perd\u00e3o&#8230;<\/p>\n<p style=\"font-weight: 400;\">O Evangelho de hoje faz liga\u00e7\u00e3o muito forte com o texto da carta aos romanos: \u201cJesus andava visitando todas as cidades e povoados, ensinando e curando todo tipo de doen\u00e7a. Quando Jesus viu a multid\u00e3o teve pena daquela gente pois estavam aflitos tal ovelhas sem pastor&#8230;\u201d Deus nos amou porque viu nossa fragilidade, nossa afli\u00e7\u00e3o e nosso pecado. O que atraiu a aten\u00e7\u00e3o de Deus foi sermos incapazes de nos guiarmos por nossa conta. Por isso Ele se coloca como pastor. Mas Ele n\u00e3o tem s\u00f3 piedade de n\u00f3s. Ele nos ama e nos ensina para irmos e seguirmos confiantes e fi\u00e9is.<\/p>\n<p style=\"font-weight: 400;\">No cen\u00e1rio do texto do Evangelho temos: pessoas aflitas, abandonadas, desamparadas, ovelhas sem pastor&#8230; pessoas sem ter quem as cuidasse. Jesus tem compaix\u00e3o delas, ent\u00e3o acontece: an\u00fancio da boa nova, ensino, cura das enfermidades&#8230; No texto tamb\u00e9m acontece chamado e envio. Podemos pensar at\u00e9 que era algo somente para os disc\u00edpulos. No entanto \u00e9 para todas as pessoas que confessam sua f\u00e9 em Jesus Cristo. Pois Ele olha para n\u00f3s, se compadece, age graciosamente em nosso favor e nos envia&#8230;<\/p>\n<p style=\"font-weight: 400;\">As pessoas seguidoras de Jesus s\u00e3o as enviadas para a seara, para agir no mundo, anunciar a boa nova, viver a compaix\u00e3o, edificar Comunidade. A comunidade \u00e9 o lugar onde a obra de Jesus continua e dela se espalha para o mundo, para a realidade de vida das pessoas.<\/p>\n<p style=\"font-weight: 400;\">A compaix\u00e3o de Jesus \u00e9 o centro de nosso texto&#8230; A partir da compaix\u00e3o \u00e9 que se edifica a comunidade, se vive o reino de amor e justi\u00e7a. A\u00ed est\u00e1 o motivo para sermos comunidade, pois ali nos encontramos, nos olhamos, nos enxergamos, nos sentimos, temos uma conviv\u00eancia de proximidade, podemos conversar, nos conhecer, exercitar empatia, se visitar, se ajudar e estender esta ajuda as demais pessoas que carecem de cuidado e amparo. Em comunidade fortalecemos o pertencimento (e n\u00e3o a posse) e o comprometimento m\u00fatuo&#8230;<\/p>\n<p style=\"font-weight: 400;\">Quando a comunidade \u00e9 edificada a partir da compaix\u00e3o, ela serve. Pessoas crist\u00e3s olham para as que est\u00e3o desamparadas, perdidas, angustiadas, em sofrimento, com o mesmo olhar de compaix\u00e3o que Jesus as olhou e se aproximou, amou, ensinou, curou, restaurou, serviu&#8230;<\/p>\n<p style=\"font-weight: 400;\">\u00c9 no servi\u00e7o em amor, no agir diaconal da comunidade, que a transforma\u00e7\u00e3o de vidas acontece, pois \u00e9 nossa resposta ao agir de compaix\u00e3o que Deus, em Jesus Cristo, teve por n\u00f3s&#8230; \u00c9 na Diaconia que a miss\u00e3o de Deus se concretiza, n\u00f3s somos parte dela. Afinal, Deus nos ama, por isso amamos!<\/p>\n<p style=\"font-weight: 400;\">Como pessoas que est\u00e3o sob o olhar de compaix\u00e3o de Jesus, temos seu Minist\u00e9rio como inspirador, como modelo para assumirmos o envio que Ele nos fez e darmos continuidade \u00e0 sua obra.<\/p>\n<p style=\"font-weight: 400;\">\u00c9 o amor que possibilitar\u00e1 que sempre nos reencontremos em nossa vida comunit\u00e1ria e assim nos fortalecermos para, com amor, compaix\u00e3o e empatia, darmos continuidade a obra de Jesus Cristo no mundo.<\/p>\n<p style=\"font-weight: 400;\">\u201c&#8230;A paz de Deus, que excede todo o entendimento, guardar\u00e1 os vossos cora\u00e7\u00f5es e as vossas mentes em Cristo Jesus\u201d. Filipenses 4.7. Am\u00e9m.<\/p>\n<hr \/>\n<p style=\"font-weight: 400;\"><strong>Pastor Marcos Aur\u00e9lio de Oliveira.<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>Chapec\u00f3 \u2013 Santa Catarina (Brasilien)<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>E-mail: <a href=\"mailto:marcos@luteranos.com.br\">marcos@luteranos.com.br<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PR\u00c9DICA PARA O 3. DOMINGO AP\u00d3S PENTECOSTES \u2013 18.06.2023 | Mateus 9. 35-10.8 | Marcos Aur\u00e9lio de Oliveira | \u201cA gra\u00e7a do Senhor Jesus Cristo, e o amor de Deus, e a comunh\u00e3o do Esp\u00edrito Santo sejam com todos v\u00f3s.\u201d 2 Cor\u00edntios 13.13. Am\u00e9m. Prezada comunidade! Irm\u00e3os e irm\u00e3s! Liturgicamente hoje estamos no terceiro domingo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15855,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36,157,853,108,193,1443,3,112,109],"tags":[],"beitragende":[],"predigtform":[],"predigtreihe":[],"bibelstelle":[],"class_list":["post-18299","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-matthaeus","category-beitragende","category-bibel","category-current","category-kapitel-9-chapter-9-matthaeus","category-marcos-aurelio-de-oliveira","category-nt","category-port","category-predigten"],"_links":{"self":[{"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/posts\/18299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/comments?post=18299"}],"version-history":[{"count":1,"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/posts\/18299\/revisions"}],"predecessor-version":[{"id":18300,"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/posts\/18299\/revisions\/18300"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/media\/15855"}],"wp:attachment":[{"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/media?parent=18299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/categories?post=18299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/tags?post=18299"},{"taxonomy":"beitragende","embeddable":true,"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/beitragende?post=18299"},{"taxonomy":"predigtform","embeddable":true,"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/predigtform?post=18299"},{"taxonomy":"predigtreihe","embeddable":true,"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/predigtreihe?post=18299"},{"taxonomy":"bibelstelle","embeddable":true,"href":"https:\/\/www.theologie.uzh.ch\/apps\/gpi\/wp-json\/wp\/v2\/bibelstelle?post=18299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}